{"id":11470,"date":"2025-08-01T10:01:51","date_gmt":"2025-08-01T13:01:51","guid":{"rendered":"https:\/\/portaldecampomaior.com.br\/noticias\/?p=11470"},"modified":"2025-08-01T10:19:01","modified_gmt":"2025-08-01T13:19:01","slug":"feminicidio-mototaxista-qu-matou-esposa-com-tiro-de-espingarda-comeca-a-cumprir-pena-de-16-anos-e-4-meses","status":"publish","type":"post","link":"https:\/\/portaldecampomaior.com.br\/noticias\/2025\/08\/01\/feminicidio-mototaxista-qu-matou-esposa-com-tiro-de-espingarda-comeca-a-cumprir-pena-de-16-anos-e-4-meses\/","title":{"rendered":"FEMINIC\u00cdDIO: Mototaxista que matou esposa com tiro de espingarda come\u00e7a a cumprir pena de 16 anos e 4 meses"},"content":{"rendered":"<div id=\"porta-1614386122\" class=\"porta-antes-do-conteudo porta-entity-placement\"><img src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon.jpg\" alt=\"\"  srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon.jpg 785w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon-300x76.jpg 300w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon-150x38.jpg 150w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon-768x196.jpg 768w\" sizes=\"(max-width: 785px) 100vw, 785px\" width=\"700\" height=\"230\"  style=\"display: inline-block;\" \/><\/div>\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-6ebef4b4799b4bc16e14cb410684de46\">O mototaxista Francisco Magno Soares Reis, vulgo Louro, que assassinou a pr\u00f3pria esposa dentro da resid\u00eancia, localizada em frente ao A\u00e7ude Grande na BR-343, no bairro de F\u00e1tima, em Campo Maior, come\u00e7ou a cumpri a pena de 16 anos e 4 meses de pris\u00e3o na Penitenci\u00e1ria Regional de Campo Maior.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"648\" height=\"500\" src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi3.jpg\" alt=\"\" class=\"wp-image-11478\" srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi3.jpg 648w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi3-300x231.jpg 300w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi3-150x116.jpg 150w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-6e8119aa1746ed4921632077412bbf6d\"><strong>ESTAVA EM LIBERDADE<br><\/strong>Louro, que esperou seu julgamento em liberdade, foi preso logoap\u00f3s receber a senten\u00e7a do Tribunal de J\u00fari de Campo Maior, nessa quinta-feira, 31.07. Do F\u00f3rum ele foi levado pela Pol\u00edcia Militar para a Delegacia Seccional.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-1f3ad311db3629cdc261304bc28d50c0\"><strong>PROCEDIMENTOS<br><\/strong>J\u00e1 nessa manh\u00e3 de sexta-feira, 01.08, Louro foi levado para uma audi\u00eancia de custodia e para exame de corpo de delito e depois desses procedimentos ia ser conduzido para Penitenci\u00e1ria Regional onde ficar\u00e1 preso em regime fechado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"648\" height=\"425\" src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi1.jpg\" alt=\"\" class=\"wp-image-11472\" srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi1.jpg 648w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi1-300x197.jpg 300w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi1-150x98.jpg 150w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-0d3a89db41c847a4a200f991e75740c5\"><strong>O CRIME<br><\/strong>Louro matou, em julho de 2021, a esposa identificada como Maria de Nazar\u00e9 dos Reis Santos, de 50 anos, com um tiro de espingarda. O tiro atingiu o pesco\u00e7o da v\u00edtima, que morreu imediatamente ap\u00f3s o disparo.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-de10a8d86df5d27e33f6ddb7a3d7f2ac\"><strong>O MOTIVO<\/strong><br>O tiro foi disparado ap\u00f3s uma discuss\u00e3o entre Louro e a esposa que bebiam juntos. Louro n\u00e3o teria concordado com o fim do relacionamento. Durante o julgamento a defesa do motot\u00e1xi alegou que a arma disparou acidentalmente. &nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"644\" height=\"454\" src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi2.jpg\" alt=\"\" class=\"wp-image-11473\" srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi2.jpg 644w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi2-300x211.jpg 300w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/08\/mototaxi2-150x106.jpg 150w\" sizes=\"(max-width: 644px) 100vw, 644px\" \/><\/figure>\n<div id=\"porta-3982478919\" class=\"porta-depois-do-conteudo porta-entity-placement\"><img src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco.jpg\" alt=\"\"  srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco.jpg 874w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco-300x97.jpg 300w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco-150x49.jpg 150w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco-768x250.jpg 768w\" sizes=\"(max-width: 874px) 100vw, 874px\" width=\"874\" height=\"284\"  style=\"display: inline-block;\" \/><\/div>","protected":false},"excerpt":{"rendered":"<p>O mototaxista Francisco Magno Soares Reis, vulgo Louro, que assassinou a pr\u00f3pria esposa dentro da resid\u00eancia, localizada em frente ao A\u00e7ude Grande na BR-343, no bairro de F\u00e1tima, em Campo Maior, come\u00e7ou a cumpri a pena de 16 anos e 4 meses de pris\u00e3o na Penitenci\u00e1ria Regional de Campo Maior. ESTAVA EM LIBERDADELouro, que esperou [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11471,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10238429342624910_103818105005019":"","facebook_10238429342624910_17841445120950023":"","facebook_10238429342624910_218395188242064":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-11470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-policial"],"_links":{"self":[{"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/posts\/11470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=11470"}],"version-history":[{"count":5,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/posts\/11470\/revisions"}],"predecessor-version":[{"id":11479,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/posts\/11470\/revisions\/11479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/media\/11471"}],"wp:attachment":[{"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=11470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=11470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=11470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}