{"id":877,"date":"2024-02-28T01:30:03","date_gmt":"2024-02-28T01:30:03","guid":{"rendered":"https:\/\/portaldecampomaior.com.br\/noticias\/?p=877"},"modified":"2024-02-28T01:45:23","modified_gmt":"2024-02-28T01:45:23","slug":"policia-apreende-dinheiro-maconha-crack-e-cocaina-durante-operacao-craco-96-em-campo-maior","status":"publish","type":"post","link":"https:\/\/portaldecampomaior.com.br\/noticias\/2024\/02\/28\/policia-apreende-dinheiro-maconha-crack-e-cocaina-durante-operacao-craco-96-em-campo-maior\/","title":{"rendered":"Pol\u00edcia apreende dinheiro, maconha, crack e coca\u00edna durante opera\u00e7\u00e3o CRACO 96 em Campo Maior"},"content":{"rendered":"<div id=\"porta-3789948593\" class=\"porta-antes-do-conteudo porta-entity-placement\"><img src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon.jpg\" alt=\"\"  srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon.jpg 785w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon-300x76.jpg 300w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon-150x38.jpg 150w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/11\/paraibaon-768x196.jpg 768w\" sizes=\"(max-width: 785px) 100vw, 785px\" width=\"700\" height=\"230\"  style=\"display: inline-block;\" \/><\/div>\n<p>A Pol\u00edcia Civil do Piau\u00ed, durante a opera\u00e7\u00e3o DRACO-96 \u201cRota Caipira\u201d, realizada na manh\u00e3 desta ter\u00e7a-feira, 27\/02 em Campo Maior, apreendeu dinheiro, maconha, crack e coca\u00edna. As investiga\u00e7\u00f5es apontam a pr\u00e1tica de tr\u00e1fico internacional de drogas, organiza\u00e7\u00e3o criminosa e lavagem de dinheiro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"604\" height=\"490\" src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/02\/presograco1-4.jpg\" alt=\"\" class=\"wp-image-895\" srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/02\/presograco1-4.jpg 604w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/02\/presograco1-4-300x243.jpg 300w\" sizes=\"(max-width: 604px) 100vw, 604px\" \/><figcaption class=\"wp-element-caption\">Erlim um dos principais investigados<\/figcaption><\/figure>\n\n\n\n<p>A Opera\u00e7\u00e3o foi deflagrada para o cumprimento de 18 mandados de pris\u00e3o e busca e apreens\u00e3o domiciliar nos estados do Piau\u00ed, S\u00e3o Paulo e Mato Grosso do Sul. Em Campo Maior foram realizadas as pris\u00f5es de tr\u00eas pessoas: Wesley Costa de Sousa, vulgo Erlim, Denner Carrerinha e Vardilany, vulgo Lane. Mas a pol\u00edcia ainda prendeu ainda um campomaiorense identificado como La\u00e9rcio, em S\u00e3o Paulo.<\/p>\n\n\n\n<p>Segundo a Pol\u00edcia Civil, al\u00e9m de Campo Maior os mandados tamb\u00e9m foram cumpridos nas cidades de Teresina, Altos e Coivaras, no estado do Piau\u00ed. &#8220;A Delegacia Seccional de Campo Maior deu apoio ao cumprimento dos mandados e demais dilig\u00eancias&#8221;, ressalta o delegado seccional Carlos J<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"642\" height=\"500\" src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/02\/presograco-2.jpg\" alt=\"\" class=\"wp-image-893\" srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/02\/presograco-2.jpg 642w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2024\/02\/presograco-2-300x234.jpg 300w\" sizes=\"(max-width: 642px) 100vw, 642px\" \/><figcaption class=\"wp-element-caption\">Carreirinha tamb\u00e9m foi preso durante opera\u00e7\u00e3o em Campo Maior<\/figcaption><\/figure>\n<div id=\"porta-197928772\" class=\"porta-depois-do-conteudo porta-entity-placement\"><img src=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco.jpg\" alt=\"\"  srcset=\"https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco.jpg 874w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco-300x97.jpg 300w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco-150x49.jpg 150w, https:\/\/portaldecampomaior.com.br\/noticias\/wp-content\/uploads\/2025\/02\/saofrancisco-768x250.jpg 768w\" sizes=\"(max-width: 874px) 100vw, 874px\" width=\"874\" height=\"284\"  style=\"display: inline-block;\" \/><\/div>","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil do Piau\u00ed, durante a opera\u00e7\u00e3o DRACO-96 \u201cRota Caipira\u201d, realizada na manh\u00e3 desta ter\u00e7a-feira, 27\/02 em Campo Maior, apreendeu dinheiro, maconha, crack e coca\u00edna. As investiga\u00e7\u00f5es apontam a pr\u00e1tica de tr\u00e1fico internacional de drogas, organiza\u00e7\u00e3o criminosa e lavagem de dinheiro. A Opera\u00e7\u00e3o foi deflagrada para o cumprimento de 18 mandados de pris\u00e3o e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":878,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10238429342624910_103818105005019":"","facebook_10238429342624910_17841445120950023":"","facebook_10238429342624910_218395188242064":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-policial"],"_links":{"self":[{"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/posts\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=877"}],"version-history":[{"count":6,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/posts\/877\/revisions"}],"predecessor-version":[{"id":897,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/posts\/877\/revisions\/897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/media\/878"}],"wp:attachment":[{"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldecampomaior.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}